{"id":17947,"date":"2024-01-04T17:38:56","date_gmt":"2024-01-04T16:38:56","guid":{"rendered":"https:\/\/fujifilmprint.eu\/lp\/cprintlyon24\/"},"modified":"2024-01-11T15:50:33","modified_gmt":"2024-01-11T14:50:33","slug":"cprintlyon24","status":"publish","type":"lp","link":"https:\/\/fujifilmprint.eu\/pt-pt\/lp\/cprintlyon24\/","title":{"rendered":"C!Print Lyon 2024"},"content":{"rendered":"<section id=\"study-header\">\r\n\t<div class=\"container-fluid black-pt\" style=\"background-image: url('https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/10\/wideformatsector-headerbanner-2500x833-1.jpg');background-size: cover;padding: 0;\">\r\n\t<div class=\"overlay\" style=\"padding: 200px 0;\">\t\t<div class=\"container\">\r\n\t\t\t<h3>\r\n\t\t\t\tFujifilm \u00e0\t\t\t<\/h3>\r\n\t\t\t<h2>\r\n\t\t\t\tC!Print Lyon 2024\t\t\t<\/h2>\r\n\t\t<\/div>\r\n\t<\/div>\t<\/div>\r\n<\/section>\n\n<div style=\"height:20px;\">\n<\/div>\n\n<section id=\"tc-icons\">\n\t<div class=\"container block-three-column-icons\">\n\t\t<h2><\/h2>\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/time.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Data<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">6 - 8 de fevereiro<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/location_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Localiza\u00e7\u00e3o<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Eurexpo Lyon<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/stand.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Stand<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">1D14<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<div style=\"height:20px;\">\n<\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3>Sal\u00e3o de beleza<\/h3>\n\t\t<h2>No stand: Impress\u00e3o de Labeur<\/h2>\n\t\t<p><\/p>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-6 my-auto\">\n\n\t\t\t\t<h3>Revoria Press PC1120<\/h3>\n\t\t\t\t<div >\n\t\t\t\t\t<p>Descubra um potencial criativo ilimitado com 10 cores, como o Or, o Argent, o Blanc, o Rose Fluo e o Clear, facilmente configur\u00e1veis nos 6 grupos de impress\u00e3o. Uma qualidade de impress\u00e3o \u00e0 altura da ind\u00fastria, uma polival\u00eancia incr\u00edvel de suportes e op\u00e7\u00f5es de acabamento e a mais vasta gama de cores CMJN. <a href=\"https:\/\/fujifilmprint.eu\/fr\/product\/revoria-press-pc1120\/\">Para saber mais.<\/a><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-6 my-auto\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/07\/theprintshowlandingpage-revoriapc1120image-800x557-2.jpg\" style=\"width: 100%\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3><\/h3>\n\t\t<h2><\/h2>\n\t\t<p><p>A imprensa <a href=\"https:\/\/fujifilmprint.eu\/fr\/product\/revoria-press-ec1100\/\">Revoria EC1100<\/a> ser\u00e1 igualmente apresentado.<\/p>\n<\/p>\n\t<\/div>\n<\/section>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3><\/h3>\n\t\t<h2>No stand: Grande Formato<\/h2>\n\t\t<p><\/p>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-6 my-auto order-md-2\">\n\n\t\t\t\t<h3>Acuity Ultra Hybrid LED<\/h3>\n\t\t\t\t<div >\n\t\t\t\t\t<p>M\u00e1quina de impress\u00e3o de grande formato Premium de 3,3 m, que oferece uma excelente qualidade de impress\u00e3o em rolo e r\u00edgida com uma excelente polival\u00eancia. <a href=\"https:\/\/fujifilmprint.eu\/fr\/product\/ultra-hybrid-led\/\">Clique aqui para mais informa\u00e7\u00f5es.<\/a><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-6 my-auto order-md-1\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2024\/01\/ultrahybrid-cprintlandingpage-1000x795-1.jpg\" style=\"width: 100%\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3><\/h3>\n\t\t<h2><\/h2>\n\t\t<p><p>Apresentamos tamb\u00e9m <a href=\"https:\/\/fujifilmprint.eu\/fr\/product\/acuity-prime-hybrid\/\">l'Acuity Prime Hybrid<\/a> et <a href=\"https:\/\/fujifilmprint.eu\/fr\/product\/acuity-prime\/\">l'Acuity Prime 30<\/a>.<\/p>\n<\/p>\n\t<\/div>\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<div id=\"contact\"><\/div>\n\n<section id=\"dark-form\">\n\t<div id=\"footer-form\" class=\"container\">\n\t\t<h2>Est\u00e1 interessado no C!Print Lyon 2024? Diga-nos o que \u00e9:<\/h2>\n\n\t\t  MktoForms2.loadForm(\u201c\/\/info.fujifilm.eu\u201d, \u201c060-MIY-956\u201d, 5280);\n\t\t<div id=\"confirmform\" style=\"visibility:hidden;\">\n                            <p><strong>\n\t\t\t\t\tObrigado pela sua pergunta, algu\u00e9m entrar\u00e1 em contato em breve.\t\t\t\t\t<\/strong><\/p>\n              \n        <\/div>\n\t<\/div>\n<\/section>","protected":false},"template":"","class_list":["post-17947","lp","type-lp","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C!Print Lyon 2024 | Fujifilm Print EMEA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fujifilmprint.eu\/pt-pt\/lp\/cprintlyon24\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C!Print Lyon 2024 | Fujifilm Print EMEA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fujifilmprint.eu\/pt-pt\/lp\/cprintlyon24\/\" \/>\n<meta property=\"og:site_name\" content=\"Fujifilm Print EMEA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-11T14:50:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/fr\\\/lp\\\/cprintlyon24\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/fr\\\/lp\\\/cprintlyon24\\\/\",\"name\":\"C!Print Lyon 2024 | Fujifilm Print EMEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\"},\"datePublished\":\"2024-01-04T16:38:56+00:00\",\"dateModified\":\"2024-01-11T14:50:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/fr\\\/lp\\\/cprintlyon24\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fujifilmprint.eu\\\/fr\\\/lp\\\/cprintlyon24\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/fr\\\/lp\\\/cprintlyon24\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landing Pages\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C!Print Lyon 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"name\":\"Fujifilm Print EMEA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fujifilmprint.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\",\"name\":\"Fujifilm Print EMEA\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"contentUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"width\":416,\"height\":70,\"caption\":\"Fujifilm Print EMEA\"},\"image\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C!Print Lyon 2024 | Fujifilm Print EMEA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fujifilmprint.eu\/pt-pt\/lp\/cprintlyon24\/","og_locale":"pt_PT","og_type":"article","og_title":"C!Print Lyon 2024 | Fujifilm Print EMEA","og_url":"https:\/\/fujifilmprint.eu\/pt-pt\/lp\/cprintlyon24\/","og_site_name":"Fujifilm Print EMEA","article_modified_time":"2024-01-11T14:50:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fujifilmprint.eu\/fr\/lp\/cprintlyon24\/","url":"https:\/\/fujifilmprint.eu\/fr\/lp\/cprintlyon24\/","name":"C!Print Lyon 2024 | Fujifilm Print EMEA","isPartOf":{"@id":"https:\/\/fujifilmprint.eu\/#website"},"datePublished":"2024-01-04T16:38:56+00:00","dateModified":"2024-01-11T14:50:33+00:00","breadcrumb":{"@id":"https:\/\/fujifilmprint.eu\/fr\/lp\/cprintlyon24\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fujifilmprint.eu\/fr\/lp\/cprintlyon24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fujifilmprint.eu\/fr\/lp\/cprintlyon24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fujifilmprint.eu\/"},{"@type":"ListItem","position":2,"name":"Landing Pages","item":"https:\/\/fujifilmprint.eu\/lp\/"},{"@type":"ListItem","position":3,"name":"C!Print Lyon 2024"}]},{"@type":"WebSite","@id":"https:\/\/fujifilmprint.eu\/#website","url":"https:\/\/fujifilmprint.eu\/","name":"Fujifilm Print EMEA","description":"","publisher":{"@id":"https:\/\/fujifilmprint.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fujifilmprint.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/fujifilmprint.eu\/#organization","name":"Fujifilm Print EMEA","url":"https:\/\/fujifilmprint.eu\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/","url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","contentUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","width":416,"height":70,"caption":"Fujifilm Print EMEA"},"image":{"@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fujifilmprint.eu\/pt-pt\/wp-json\/wp\/v2\/lp\/17947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fujifilmprint.eu\/pt-pt\/wp-json\/wp\/v2\/lp"}],"about":[{"href":"https:\/\/fujifilmprint.eu\/pt-pt\/wp-json\/wp\/v2\/types\/lp"}],"wp:attachment":[{"href":"https:\/\/fujifilmprint.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=17947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}