{"id":13025,"date":"2023-04-27T10:18:04","date_gmt":"2023-04-27T10:18:04","guid":{"rendered":"https:\/\/fujifilmprint.eu\/?post_type=resource&#038;p=13025"},"modified":"2024-03-22T16:58:29","modified_gmt":"2024-03-22T15:58:29","slug":"oedim-ultra","status":"publish","type":"resource","link":"https:\/\/fujifilmprint.eu\/it\/resource\/oedim-ultra\/","title":{"rendered":"Oedim: Acuity Ultra R2"},"content":{"rendered":"<section id=\"study-header\">\r\n\t<div class=\"container-fluid black-pt\" style=\"background-image: url('https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-banner-2500x800-1.jpg');background-size: cover;padding: 0;\">\r\n\t<div class=\"overlay\" style=\"padding: 200px 0;\">\t\t<div class=\"container\">\r\n\t\t\t<h3>\r\n\t\t\t\tCaso di studio: Acuity Ultra R2\t\t\t<\/h3>\r\n\t\t\t<h2>\r\n\t\t\t\tOedim\t\t\t<\/h2>\r\n\t\t<\/div>\r\n\t<\/div>\t<\/div>\r\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3>Argomento di studio<\/h3>\n\t\t<h2>Lo specialista del grande formato Oedim potenzia il suo parco stampanti Acuity \u2018superwide\u2019 investendo in una stampante a getto d'inchiostro Acuity Ultra R2<\/h2>\n\t\t<p><\/p>\n\t<\/div>\n<\/section>\n\n<section id=\"tc-icons\">\n\t<div class=\"container block-three-column-icons\">\n\t\t<h2><\/h2>\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/customer_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong><\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Oedim<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/location_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong><\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Ja\u00e9n, Spagna<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/Products_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong><\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Acuity Ultra R2<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<div style=\"height:20px;\">\n<\/div>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t<h3>Punti salienti<\/h3>\n\t\t\t\t<div class=\"txt-cols\">\n\t\t\t\t\t<ul>\n<li style=\"text-align: left\"><a href=\"https:\/\/www.oedim.com\/\" target=\"_blank\" rel=\"noopener\">Oedim<\/a> investito in un'azienda di 5m <a href=\"\/it\/product\/acuity-ultra-r2\/\">Acuity Ultra R2<\/a> per sostenere la crescita delle imprese.<\/li>\n<li style=\"text-align: left\">L'azienda disponeva gi\u00e0 di quattro macchine da stampa Acuity Ultra.<\/li>\n<li style=\"text-align: left\">Il successo dei precedenti modelli Acuity Ultra e l'eccellente rapporto con Fujifilm ne hanno fatto una scelta ovvia.<\/li>\n<li style=\"text-align: left\">La nuova macchina da stampa sar\u00e0 utilizzata per la stampa di annunci pubblicitari, insegne e coperture di edifici.<\/li>\n<li style=\"text-align: left\">L'azienda \u00e8 orgogliosa di offrire versatilit\u00e0 e valore ai propri clienti.<\/li>\n<li style=\"text-align: left\">Oedim \u00e8 stata soddisfatta del buon servizio costante ricevuto da Fujifilm.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<div style=\"height:20px;\">\n<\/div>\n\n<section id=\"testimonial-v1\">\n\t<div class=\"container-fluid\">\n\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-md-1\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/themes\/poi\/media\/quote-white.svg\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-md-11\">\n\t\t\t\t\t<div class=\"testiv1-inner\">\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\tL'investimento in un'altra stampante Fujifilm ha rafforzato la nostra fiducia nell'azienda come partner affidabile e fidato.\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"name\">\n\t\t\t\t\t\t\t\tMiguel \u00c1ngel G\u00f3mez Cano | Direttore generale, Oedim\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<\/section>\t\n\n<section id=\"txt-vid\" style=\"background: linear-gradient(to bottom,,);\">\n\t<div class=\"container-fluid\" style=\"background-image: url(); background-position: ; padding: 50px;\">\n\t\t<div class=\"container\">\n\t\t\t<h2 style=\"margin-bottom: 20px;\">Guarda il video<\/h2>\n\t\t\t<div class=\"dash-1\" style=\"display: none;\"><\/div>\n\t\t\t<p><\/p>\n\t\t\t<div class=\"center\">\n\t\t\t\t<video controls preload=\"none\" poster=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-videothumbnail-1280x720-1.jpg\" width=\"680\">\n\t\t\t\t<source src=\"\t\t\t\thttps:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-Short-Film-Italian.mp4\t\t\t\t\" type=\"video\/mp4\">\n\t\t\t\t<\/video>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-6 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p>Lo specialista spagnolo del grande formato Oedim ha nuovamente collaborato con Fujifilm per espandere la propria flotta di <a href=\"\/it\/settore-del-grande-formato\/\">Stampanti di grande formato Acuity<\/a> per aumentare la produttivit\u00e0 e sostenere la propria crescita. L'azienda, che possiede gi\u00e0 quattro stampanti Acuity Ultra, ha recentemente investito in una \u2018superwide\u2019 da 5 metri.\u2019 <a href=\"\/it\/product\/acuity-ultra-r2\/\">Stampante a getto d'inchiostro Acuity Ultra R2<\/a>. La nuova stampante, installata presso la sede di Ja\u00e9n (Spagna) su una superficie di 20.000 metri quadrati, sar\u00e0 utilizzata prevalentemente per la stampa di pubblicit\u00e0 di grande formato su tele, oltre che per la segnaletica di eventi e per la decorazione di edifici.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-6 my-auto\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-image1-773x515-1.jpg\" style=\"width: 100%\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto order-md-2\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p>Fondata nel 1996, Oedim \u00e8 un'azienda specializzata nella stampa di grande formato che d\u00e0 priorit\u00e0 alla personalizzazione e all'efficienza, offrendo al contempo versatilit\u00e0 e valore. Molti dei suoi clienti operano nei settori del marketing e della pubblicit\u00e0 e richiedono stampe di grande formato su substrati quali vinile, cartone, teloni, tessuti e altro ancora.<\/p>\n<p>Oedim ha cercato un'altra stampante per grandi formati Fujifilm perch\u00e9 era soddisfatta della qualit\u00e0 e dell'affidabilit\u00e0 delle sue macchine Acuity Ultra. Era inoltre molto soddisfatta dell'assistenza ricevuta da Fujifilm.<\/p>\n<p>Il <a href=\"\/it\/product\/acuity-ultra-r2\/\">Stampante a getto d'inchiostro Acuity Ultra R2<\/a>, La stampante Fujifilm, che fa parte della nuova gamma di stampanti per grandi formati, \u00e8 disponibile nelle configurazioni \u2018superwide\u2019 da 5 m e standard da 3,2 m, e nelle configurazioni UV Mercury e UV LED. Progettata da zero, pensando all'operatore, si \u00e8 aggiudicata <a href=\"https:\/\/www.red-dot.org\/\" target=\"_blank\" rel=\"noopener\">Punto rosso<\/a>, <a href=\"https:\/\/www.good-designawards.com\/\" target=\"_blank\" rel=\"noopener\">Buon design<\/a> e <a href=\"https:\/\/ifdesign.com\/en\/winner-ranking\/project\/acuity-ultra-r2\/331227\" target=\"_blank\" rel=\"noopener\">iF<\/a> per le sue impeccabili caratteristiche di design.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<div style=\"height:20px;\">\n<\/div>\n\n\n<style>\n#fw-image {\n    width: 100%;\n}\n\n#fw-image .fw-img-wrapper {\n    width: 100%;\n    display: flex;\n    justify-content: flex-start;\n}\n\n#fw-image img {\n    width: 100%;\n    height: auto;\n    object-fit: contain;\n}\n<\/style>\n\n<section id=\"fw-image\">\n    <div class=\"fw-img-wrapper\">\n        <picture>\n            <source media=\"(max-width: 768px)\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-banner2-2500x800-1.jpg\">\n            <img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-banner2-2500x800-1.jpg\" alt=\"\">\n        <\/picture>\n    <\/div>\n<\/section>\n\n<div style=\"height:20px;\">\n<\/div>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p>Miguel \u00c1ngel G\u00f3mez Cano, amministratore delegato di Oedim, afferma: \u201cIn Oedim, le stampe di grande formato sono la nostra specialit\u00e0. Molti dei nostri clienti operano nei settori del marketing e della pubblicit\u00e0 e richiedono stampe di grande formato, sia su tessuti, vinile, cartone o teloni. L'investimento in una Acuity Ultra R2 ci ha permesso di dare priorit\u00e0 alla personalizzazione e all'efficienza, garantendo al contempo versatilit\u00e0 e valore, il tutto in un'ottica di crescita.\u201d<\/p>\n<p>\u201cOra, con una Acuity Ultra R2 inclusa nel nostro parco stampanti, possiamo offrire ai nostri clienti un servizio ancora pi\u00f9 veloce e affidabile, in particolare quando si tratta di stampe \u2018superwide\u2019 da 5 metri. La macchina non \u00e8 solo intuitiva e facile da usare, ma \u00e8 anche affidabile e offre una qualit\u00e0 eccezionale. Questo \u00e8 dimostrato dal fatto che la utilizziamo prevalentemente per stampare su rete e tele e su tele per eventi. \u201d<\/p>\n<p>Cano afferma: \u201cIl nostro investimento in un'altra stampante Fujifilm ha rafforzato la nostra fiducia nell'azienda come partner fidato e affidabile\u201d.\u201d<\/p>\n<p><span>Joan Casas, Manager di Fujifilm Graphic Communications, Spagna, commenta: \u201cSiamo entusiasti che la Acuity Ultra R2 stia aiutando Oedim a soddisfare le esigenze dei suoi clienti e li ringraziamo per essere un partner fedele della Fujifilm\u201d.\u201d\u00a0<\/span><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13036 aligncenter\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Fujifilm-oedim-logos-1000x166-1.png\" alt=\"\" width=\"1000\" height=\"166\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Fujifilm-oedim-logos-1000x166-1.png 1000w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Fujifilm-oedim-logos-1000x166-1-300x50.png 300w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Fujifilm-oedim-logos-1000x166-1-768x127.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"form-bg\">\n\t<div class=\"slider-fade\">\n\t\t\t\t\t\t\t\t\t<div class=\"container-fluid block-short-cta-form\" style=\"background-image: url(https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/Acuity-Ultra-R2-Banner-scaled.jpg); background-size: cover;\">\n\t\t\t\t\t<div class=\"container\">\n\t\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t\t\t\t<h3>Acuity Ultra R2<\/h3>\n\t\t\t\t\t\t\t\t<p class=\"frm-h\">Per saperne di pi\u00f9 sull'altissima qualit\u00e0 e sulla versatilit\u00e0 della Acuity Ultra R2 e su come il suo basso consumo di inchiostro pu\u00f2 migliorare il ROI<\/p>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/fujifilmprint.eu\/it\/product\/acuity-ultra-r2\/\" class=\"btn btn-purple\">Scopri Acuity Ultra R2<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-4\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/section>\n\n<section id=\"dark-form\">\n\t<div id=\"footer-form\" class=\"container\">\n\t\t<h2>Domande? Contattateci qui sotto:<\/h2>\n\n\t\t \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  MktoForms2.loadForm(\u201c\/\/info.fujifilm.eu\u201d, \u201c060-MIY-956\u201d, 5281); \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \r\n\r\n  \r\n\r\n \n\t\t<div id=\"confirmform\" style=\"visibility:hidden;\">\n                            <p><strong>\n\t\t\t\t\tGrazie per la tua richiesta, qualcuno ti contatter\u00e0 presto.\t\t\t\t\t<\/strong><\/p>\n              \n        <\/div>\n\t<\/div>\n<\/section>","protected":false},"featured_media":13044,"template":"","sector":[37],"resource-categories":[41,42],"class_list":["post-13025","resource","type-resource","status-publish","has-post-thumbnail","hentry","sector-wide-format","resource-categories-case-study","resource-categories-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oedim: Acuity Ultra R2 Inkjet Printer | Fujifilm Print EMEA<\/title>\n<meta name=\"description\" content=\"Wide format specialist Oedim boosts its Acuity superwide printer fleet by investing in an Acuity Ultra R2 Inkjet Printer. Read and watch the case study here\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fujifilmprint.eu\/it\/resource\/oedim-ultra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oedim: Acuity Ultra R2 Inkjet Printer | Fujifilm Print EMEA\" \/>\n<meta property=\"og:description\" content=\"Wide format specialist Oedim boosts its Acuity superwide printer fleet by investing in an Acuity Ultra R2 Inkjet Printer. Read and watch the case study here\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fujifilmprint.eu\/it\/resource\/oedim-ultra\/\" \/>\n<meta property=\"og:site_name\" content=\"Fujifilm Print EMEA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T15:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-featured-1000x562-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/\",\"name\":\"Oedim: Acuity Ultra R2 Inkjet Printer | Fujifilm Print EMEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Oedim-featured-1000x562-1.jpg\",\"datePublished\":\"2023-04-27T10:18:04+00:00\",\"dateModified\":\"2024-03-22T15:58:29+00:00\",\"description\":\"Wide format specialist Oedim boosts its Acuity superwide printer fleet by investing in an Acuity Ultra R2 Inkjet Printer. Read and watch the case study here\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Oedim-featured-1000x562-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Oedim-featured-1000x562-1.jpg\",\"width\":1000,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/resource\\\/oedim-ultra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/es\\\/resource\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oedim: Acuity Ultra R2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"name\":\"Fujifilm Print EMEA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fujifilmprint.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\",\"name\":\"Fujifilm Print EMEA\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"contentUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"width\":416,\"height\":70,\"caption\":\"Fujifilm Print EMEA\"},\"image\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oedim: stampante a getto d'inchiostro Acuity Ultra R2 | Fujifilm Print EMEA","description":"Lo specialista del grande formato Oedim potenzia il suo parco stampanti Acuity superwide investendo in una stampante a getto d'inchiostro Acuity Ultra R2. Leggete e guardate il caso di studio qui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fujifilmprint.eu\/it\/resource\/oedim-ultra\/","og_locale":"it_IT","og_type":"article","og_title":"Oedim: Acuity Ultra R2 Inkjet Printer | Fujifilm Print EMEA","og_description":"Wide format specialist Oedim boosts its Acuity superwide printer fleet by investing in an Acuity Ultra R2 Inkjet Printer. Read and watch the case study here","og_url":"https:\/\/fujifilmprint.eu\/it\/resource\/oedim-ultra\/","og_site_name":"Fujifilm Print EMEA","article_modified_time":"2024-03-22T15:58:29+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-featured-1000x562-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/","url":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/","name":"Oedim: stampante a getto d'inchiostro Acuity Ultra R2 | Fujifilm Print EMEA","isPartOf":{"@id":"https:\/\/fujifilmprint.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/#primaryimage"},"image":{"@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/#primaryimage"},"thumbnailUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-featured-1000x562-1.jpg","datePublished":"2023-04-27T10:18:04+00:00","dateModified":"2024-03-22T15:58:29+00:00","description":"Lo specialista del grande formato Oedim potenzia il suo parco stampanti Acuity superwide investendo in una stampante a getto d'inchiostro Acuity Ultra R2. Leggete e guardate il caso di studio qui","breadcrumb":{"@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/#primaryimage","url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-featured-1000x562-1.jpg","contentUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/04\/Oedim-featured-1000x562-1.jpg","width":1000,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/fujifilmprint.eu\/resource\/oedim-ultra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fujifilmprint.eu\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/fujifilmprint.eu\/es\/resource\/"},{"@type":"ListItem","position":3,"name":"Oedim: Acuity Ultra R2"}]},{"@type":"WebSite","@id":"https:\/\/fujifilmprint.eu\/#website","url":"https:\/\/fujifilmprint.eu\/","name":"Fujifilm Print EMEA","description":"","publisher":{"@id":"https:\/\/fujifilmprint.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fujifilmprint.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fujifilmprint.eu\/#organization","name":"Fujifilm Print EMEA","url":"https:\/\/fujifilmprint.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/","url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","contentUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","width":416,"height":70,"caption":"Fujifilm Print EMEA"},"image":{"@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/resource\/13025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/types\/resource"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/media\/13044"}],"wp:attachment":[{"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/media?parent=13025"}],"wp:term":[{"taxonomy":"sector","embeddable":true,"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/sector?post=13025"},{"taxonomy":"resource-categories","embeddable":true,"href":"https:\/\/fujifilmprint.eu\/it\/wp-json\/wp\/v2\/resource-categories?post=13025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}