{"id":20446,"date":"2025-07-14T12:18:48","date_gmt":"2025-07-14T11:18:48","guid":{"rendered":"https:\/\/staging.fujifilmprint.eu\/?post_type=lp&#038;p=20446"},"modified":"2025-08-29T13:57:11","modified_gmt":"2025-08-29T12:57:11","slug":"labelexpo2025","status":"publish","type":"lp","link":"https:\/\/fujifilmprint.eu\/fr\/lp\/labelexpo2025\/","title":{"rendered":"Labelexpo 2025"},"content":{"rendered":"<section id=\"study-header\">\r\n\t<div class=\"container-fluid black-pt\" style=\"background-image: url('https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/07\/ADS2025_Landing-page-header-e1753865504748.jpg');background-size: cover;padding: 0;\">\r\n\t<div class=\"overlay\" style=\"padding: 200px 0;\">\t\t<div class=\"container\">\r\n\t\t\t<h3>\r\n\t\t\t\tFujifilm \u00e0\t\t\t<\/h3>\r\n\t\t\t<h2>\r\n\t\t\t\tLabelexpo 2025\t\t\t<\/h2>\r\n\t\t<\/div>\r\n\t<\/div>\t<\/div>\r\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<section id=\"tc-icons\">\n\t<div class=\"container block-three-column-icons\">\n\t\t<h2><\/h2>\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/time.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Date<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">16-19 septembre 2025<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/location_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Emplacement<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Fira Gran Via, Barcelone<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/stand.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Stand<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Hall 5 Stand D73<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<div style=\"height:20px;\">\n<\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3>Salon professionnel<\/h3>\n\t\t<h2>Nous pr\u00e9sentons notre vaste gamme de solutions d'impression analogique et num\u00e9rique \u00e0 Labelexpo 2025.<\/h2>\n\t\t<p><\/p>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p>Nous reviendrons cette ann\u00e9e \u00e0 Labelexpo, \u00e0 Barcelone, sur le stand 5D73, en poursuivant notre th\u00e8me \u2018Analogique. Num\u00e9rique. durable\u2019, en mettant l'accent sur l'innovation avec l'introduction de nouvelles technologies qui soulignent notre engagement permanent \u00e0 faire progresser l'industrie de l'\u00e9tiquetage et de l'emballage.<\/p>\n<p>Le stand comportera \u00e0 nouveau des zones analogiques et num\u00e9riques, offrant une exp\u00e9rience immersive qui refl\u00e8te l'engagement de Fujifilm \u00e0 soutenir les processus d'impression traditionnels tout en acc\u00e9l\u00e9rant son passage au num\u00e9rique.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<div id=\"speakerschedule\"><\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3><\/h3>\n\t\t<h2><\/h2>\n\t\t<p><h3><span style=\"color: #000000\">J<\/span><span style=\"color: #000000\">oignez-nous pour que nos invit\u00e9s partagent leurs secrets de r\u00e9ussite<\/span><\/h3>\n<\/p>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<h3><span style=\"color: #00e5c2\"><strong>Mardi<\/strong><\/span><\/h3>\n<p><strong>10:30 Passer au num\u00e9rique pour la production de bo\u00eetes pliantes<\/strong><br \/>\nJoakim Johansson, directeur g\u00e9n\u00e9ral de <span class=\"s11\">Karton<\/span><span class=\"s11\">g<\/span><span class=\"s11\">boulon<\/span><span class=\"s11\">un<\/span><span class=\"s11\">obtenir<\/span> AB<\/p>\n<p><strong>11:30 Flexo LIVE<\/strong><br \/>\nFidan Sari, L\u00fcscher Technologies AG<\/p>\n<p><strong>14:00 Un flux de travail d'emballage pour r\u00e9gner sur tous les flux de travail<\/strong><br \/>\nChristopher Graf, directeur g\u00e9n\u00e9ral\/VP Colour chez Hybrid Software<\/p>\n<p><strong>15:00 Jet Press - une force motrice dans l'emballage<\/strong><br \/>\nRaynald Barillot et Mark Stephenson, Fujifilm Graphic Communications EMEA<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-6 my-auto order-md-2\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<h3><span style=\"color: #00e5c2\"><strong>Mercredi<\/strong><\/span><\/h3>\n<p><strong>10:30 Passer au num\u00e9rique pour la production de bo\u00eetes pliantes<\/strong><br \/>\nJoakim Johansson, directeur g\u00e9n\u00e9ral de <span class=\"s11\">Karton<\/span><span class=\"s11\">g<\/span><span class=\"s11\">boulon<\/span><span class=\"s11\">un<\/span><span class=\"s11\">obtenir<\/span> AB<\/p>\n<p><strong>11:30 Water Wash and Go - la r\u00e9volution des plaques flexo<\/strong><br \/>\nMatt Franklow, Creation Reprographics<\/p>\n<p><strong>14:00 L'aube du num\u00e9rique dans l'emballage souple<\/strong><br \/>\nSimon Buswell, directeur des ventes et du marketing chez Eco Flexibles<\/p>\n<p><strong>15:00 Revoria Press - 5uper \u00c9preuve couleur pour pochettes et \u00e9tiquettes<\/strong><br \/>\nAlfonso Garcia, chef de produit, Fujifilm Graphic Communications EMEA<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-6 my-auto order-md-1\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/10\/flexiblepackagingarticle-image2-1000x700-1.jpg\" style=\"width: 100%\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<h3><span style=\"color: #00e5c2\"><strong>Jeudi<\/strong><\/span><\/h3>\n<p><strong>10:30 L'\u00e9nergie en baisse - la productivit\u00e9 et la durabilit\u00e9 en hausse<\/strong><br \/>\nLe texte fourni est vide. Je ne peux pas traduire un texte vide.<span class=\"s11\">Jamie <\/span><span class=\"s11\">Parker, chef des op\u00e9rations, <\/span><span class=\"s11\">Paragon ID<\/span><\/p>\n<p><strong>11:30 L'aube du num\u00e9rique dans l'emballage souple<\/strong><br \/>\nSimon Buswell, directeur des ventes et du marketing chez Eco Flexibles<\/p>\n<p><strong>14:00 C'est Belissima !<\/strong><br \/>\nDaniel Badea Directeur informatique \/ Responsable des ventes et de la mise en \u0153uvre chez Hamillroad<\/p>\n<p><strong>15:00 Jet Press - une force motrice dans l'emballage<\/strong><br \/>\nRaynald Barillot et Mark Stephenson, Fujifilm Graphic Communications EMEA<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-6 my-auto order-md-2\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<h3><span style=\"color: #00e5c2\"><strong>Vendredi<\/strong><\/span><\/h3>\n<p><strong>10:30 L'\u00e9nergie en baisse - la productivit\u00e9 et la durabilit\u00e9 en hausse<\/strong><br \/>\nLe texte fourni est vide. Je ne peux pas traduire un texte vide.<span class=\"s11\">Jamie <\/span><span class=\"s11\">Parker, chef des op\u00e9rations, <\/span><span class=\"s11\">Paragon ID<\/span><\/p>\n<p><strong>11:30 Un flux de travail d'emballage pour r\u00e9gner sur tous les flux de travail<\/strong><br \/>\nChristopher Graf, directeur g\u00e9n\u00e9ral\/VP Colour chez Hybrid Software<\/p>\n<p><strong>14:00 Revoria Press - 5uper \u00c9preuve couleur pour pochettes et \u00e9tiquettes<\/strong><br \/>\nAlfonso Garcia, chef de produit, Fujifilm Graphic Communications EMEA<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"col-md-6 my-auto order-md-1\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/10\/Folding-Carton-Packaging.jpg\" style=\"width: 100%\" \/>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<section id=\"txt-vid\" style=\"background: linear-gradient(to bottom,#000000,#000000);\">\n\t<div class=\"container-fluid\" style=\"background-image: url(); background-position: left; padding: 50px;\">\n\t\t<div class=\"container\">\n\t\t\t<h2 style=\"margin-bottom: 20px;\">Labelexpo 2023<\/h2>\n\t\t\t<div class=\"dash-1\" style=\"display: none;\"><\/div>\n\t\t\t<p>Regardez la vid\u00e9o ci-dessous, de Labelexpo 2023 qui s'est tenu \u00e0 Bruxelles, en Belgique.<\/p>\n\t\t\t<div class=\"center\">\n\t\t\t\t<video controls preload=\"none\" poster=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/08\/labelexpo-videothumbnail.jpg\" width=\"680\">\n\t\t\t\t<source src=\"\t\t\t\thttps:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/08\/Label-Expo-2023-Highlights.mp4\t\t\t\t\" type=\"video\/mp4\">\n\t\t\t\t<\/video>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<div style=\"height:50px;\">\n<\/div>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p>Dans la zone analogique, des plaques flexo seront produites en direct \u00e0 l'aide des plaques \u00e0 lavage \u00e0 l'eau Fujifilm et Flenex FW. Cette installation montrera \u00e0 quel point la fabrication de plaques de haute qualit\u00e9 peut \u00eatre rapide et efficace, avec des cycles complets de fabrication de plaques en moins de 40 minutes. Parall\u00e8lement, des d\u00e9monstrations du syst\u00e8me UV LED LuXtreme de Fujifilm et des encres et vernis CuremaX seront organis\u00e9es, soulignant l'expertise de Fujifilm dans la fourniture de solutions de production durables et \u00e9conomes en \u00e9nergie.<\/p>\n<p>Une sc\u00e8ne de pr\u00e9sentation d\u00e9di\u00e9e accueillera des sessions r\u00e9guli\u00e8res sur les avantages des solutions analogiques et num\u00e9riques de Fujifilm. Les partenaires et les utilisateurs prendront la parole pour expliquer comment les technologies de Fujifilm les ont aid\u00e9s \u00e0 se d\u00e9velopper et \u00e0 s'adapter. La Jet Press FP790, la presse num\u00e9rique \u00e0 jet d'encre \u00e0 base d'eau innovante de Fujifilm con\u00e7ue pour les emballages souples, offre une v\u00e9ritable alternative \u00e0 la flexographie sans compromis sur la qualit\u00e9 ou la conformit\u00e9 r\u00e9glementaire. La presse num\u00e9rique \u00e0 jet d'encre B2 de Fujifilm, la Jet Press 750S, de plus en plus adapt\u00e9e aux applications de bo\u00eetes pliantes, sera \u00e9galement pr\u00e9sent\u00e9e.<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n<section id=\"txt-media\">\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-12 my-auto\">\n\n\t\t\t\t\n\t\t\t\t<div >\n\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20447 alignright\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-1024x522.jpg\" alt=\"\" width=\"457\" height=\"233\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-1024x522.jpg 1024w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-300x153.jpg 300w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-768x392.jpg 768w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-1536x784.jpg 1536w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-2048x1045.jpg 2048w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/06\/5UPER-COLOUR-video-thumb2-scaled-e1749742932314-18x9.jpg 18w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/p>\n<p>L'une de nos nouvelles presses 5 couleurs \u20185UPER COLOUR\u2019 sera \u00e9galement expos\u00e9e. Lanc\u00e9e r\u00e9cemment en Europe, la tr\u00e8s attendue presse Revoria SC285S de milieu de gamme est \u00e9quip\u00e9e d'une station de toner suppl\u00e9mentaire pour permettre l'impression en cinq couleurs en un seul passage. Id\u00e9ales pour les producteurs d'emballages, ces presses \u20185UPER COLOUR\u2019 offrent une production \u00e0 grande vitesse, une excellente flexibilit\u00e9 des supports et une qualit\u00e9 d'impression impressionnante qui rivalise avec l'offset, gr\u00e2ce \u00e0 une technologie de toner avanc\u00e9e et \u00e0 une imagerie laser haute r\u00e9solution.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Les solutions d'impression de Fujifilm seront \u00e9galement pr\u00e9sent\u00e9es sur le stand, mettant en \u00e9vidence leur polyvalence dans toute une s\u00e9rie d'applications d'emballage. Construites avec des t\u00eates d'impression Samba \u00e9volutives, ces solutions de barre d'impression en un seul passage \u00e9liminent le besoin de repositionnement et garantissent un fonctionnement transparent sur diff\u00e9rentes largeurs d'impression et diff\u00e9rents types de supports.<\/p>\n<p>La durabilit\u00e9 reste un th\u00e8me cl\u00e9 dans l'ensemble du portefeuille de Fujifilm. Qu'il s'agisse de plaques flexo \u00e0 lavage \u00e0 l'eau, de syst\u00e8mes d'encre UV LED ou de solutions de toner \u00e0 faible consommation d'\u00e9nergie et \u00e0 haute performance, toutes les innovations pr\u00e9sent\u00e9es \u00e0 Labelexpo ont \u00e9t\u00e9 d\u00e9velopp\u00e9es dans un souci de performance et de responsabilit\u00e9 environnementale.<\/p>\n<p>Manuel Schrutt, directeur mondial de la strat\u00e9gie commerciale, Emballage, Fujifilm, commente : \u201cAlors que notre portefeuille d'emballages ne cesse de s'\u00e9toffer, Labelexpo reste la plateforme id\u00e9ale pour pr\u00e9senter notre gamme incroyablement large de solutions. Notre concept \u2018Analogue. Digital. durable\u2019 repr\u00e9sente notre engagement strat\u00e9gique \u00e0 aider nos clients \u00e0 \u00e9voluer \u00e0 leur propre rythme. Cette ann\u00e9e, nous apportons encore plus \u00e0 la table et nous sommes ravis d'accueillir les visiteurs sur un stand qui refl\u00e8te vraiment la direction que prend l'industrie et la fa\u00e7on dont Fujifilm innove dans ce changement\u201d.\u201d<\/p>\n<h5 style=\"text-align: center\"><strong>Visitez Fujifilm dans le Hall 5 Stand D73 \u00e0 Labelexpo 2025 \u00e0 Barcelone.<\/strong><\/h5>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n<section id=\"small-cta\">\n\n<!-- Standard Block -->\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-md-6 img-bg\" style=\"background-image: url(https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2023\/03\/LabelsPack-CTA.jpg);\">\n            <\/div>\n            <div class=\"col-md-6 green\">\n                <h3>Solutions d'\u00e9tiquetage et d'emballage<\/h3>\n                <p>En savoir plus sur notre gamme d'\u00e9tiquettes et d'emballages<\/p>\n                                    <a href=\"https:\/\/fujifilmprint.eu\/fr\/label-packaging-sector\/\" id=\"btnOpenForm\" class=\"btn btn-purple\" style=\"margin: 0\">D\u00e9couvrir plus<\/a>\n                            <\/div>\n        <\/div>\n    <\/div>\n\t\n\n<\/section>\n\n\n\n<!-- Single Pop-up -->\n<div id=\"popup-\" class=\"popup\">\n\t<div class=\"popup-content dark-form\" id=\"dark-form\">\n\t\t<div class=\"event-header\">\n\t\t\t<h2>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/h2>\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"confirmform\" style=\"visibility:hidden;\">\n\t\t\t\t\t\t\t<p><strong>Merci pour votre demande, quelqu&#039;un vous contactera bient\u00f4t.<\/strong><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t<span class=\"fade-out main-btn-circle\">\u2573<\/span>\n\t<\/div>\n<\/div>\n\t\n\n\n<div id=\"contact\"><\/div>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<section id=\"dark-form\">\n\t<div id=\"footer-form\" class=\"container\">\n\t\t<h2>Faites part de votre int\u00e9r\u00eat :<\/h2>\n\n\t\t \r\n\r\n \n\t\t<div id=\"confirmform\" style=\"visibility:hidden;\">\n                            <p><strong>\n\t\t\t\t\tNous vous remercions de votre int\u00e9r\u00eat et vous donnons rendez-vous \u00e0 Labelexpo 2025.\t\t\t\t\t<\/strong><\/p>\n              \n        <\/div>\n\t<\/div>\n<\/section>","protected":false},"template":"","class_list":["post-20446","lp","type-lp","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Labelexpo 2025 | Fujifilm Print EMEA<\/title>\n<meta name=\"description\" content=\"We\u2019ll be at Labelexpo 2025 to demonstrate our growing range of analogue, digital and sustainable print solutions for the label and packaging industry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fujifilmprint.eu\/fr\/lp\/labelexpo2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Labelexpo 2025 | Fujifilm Print EMEA\" \/>\n<meta property=\"og:description\" content=\"We\u2019ll be at Labelexpo 2025 to demonstrate our growing range of analogue, digital and sustainable print solutions for the label and packaging industry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fujifilmprint.eu\/fr\/lp\/labelexpo2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fujifilm Print EMEA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T12:57:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/labelexpo2025\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/labelexpo2025\\\/\",\"name\":\"Labelexpo 2025 | Fujifilm Print EMEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\"},\"datePublished\":\"2025-07-14T11:18:48+00:00\",\"dateModified\":\"2025-08-29T12:57:11+00:00\",\"description\":\"We\u2019ll be at Labelexpo 2025 to demonstrate our growing range of analogue, digital and sustainable print solutions for the label and packaging industry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/labelexpo2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/labelexpo2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/labelexpo2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landing Pages\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Labelexpo 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"name\":\"Fujifilm Print EMEA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fujifilmprint.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\",\"name\":\"Fujifilm Print EMEA\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"contentUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"width\":416,\"height\":70,\"caption\":\"Fujifilm Print EMEA\"},\"image\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Labelexpo 2025 | Fujifilm Print EMEA","description":"Nous serons pr\u00e9sents \u00e0 Labelexpo 2025 pour pr\u00e9senter notre gamme croissante de solutions d'impression analogiques, num\u00e9riques et durables pour l'industrie de l'\u00e9tiquette et de l'emballage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fujifilmprint.eu\/fr\/lp\/labelexpo2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Labelexpo 2025 | Fujifilm Print EMEA","og_description":"We\u2019ll be at Labelexpo 2025 to demonstrate our growing range of analogue, digital and sustainable print solutions for the label and packaging industry.","og_url":"https:\/\/fujifilmprint.eu\/fr\/lp\/labelexpo2025\/","og_site_name":"Fujifilm Print EMEA","article_modified_time":"2025-08-29T12:57:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fujifilmprint.eu\/lp\/labelexpo2025\/","url":"https:\/\/fujifilmprint.eu\/lp\/labelexpo2025\/","name":"Labelexpo 2025 | Fujifilm Print EMEA","isPartOf":{"@id":"https:\/\/fujifilmprint.eu\/#website"},"datePublished":"2025-07-14T11:18:48+00:00","dateModified":"2025-08-29T12:57:11+00:00","description":"Nous serons pr\u00e9sents \u00e0 Labelexpo 2025 pour pr\u00e9senter notre gamme croissante de solutions d'impression analogiques, num\u00e9riques et durables pour l'industrie de l'\u00e9tiquette et de l'emballage.","breadcrumb":{"@id":"https:\/\/fujifilmprint.eu\/lp\/labelexpo2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fujifilmprint.eu\/lp\/labelexpo2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fujifilmprint.eu\/lp\/labelexpo2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fujifilmprint.eu\/"},{"@type":"ListItem","position":2,"name":"Landing Pages","item":"https:\/\/fujifilmprint.eu\/lp\/"},{"@type":"ListItem","position":3,"name":"Labelexpo 2025"}]},{"@type":"WebSite","@id":"https:\/\/fujifilmprint.eu\/#website","url":"https:\/\/fujifilmprint.eu\/","name":"Fujifilm Imprimer EMEA","description":"","publisher":{"@id":"https:\/\/fujifilmprint.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fujifilmprint.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fujifilmprint.eu\/#organization","name":"Fujifilm Imprimer EMEA","url":"https:\/\/fujifilmprint.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/","url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","contentUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","width":416,"height":70,"caption":"Fujifilm Print EMEA"},"image":{"@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/lp\/20446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/lp"}],"about":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/types\/lp"}],"wp:attachment":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/media?parent=20446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}