{"id":19570,"date":"2025-04-10T14:27:13","date_gmt":"2025-04-10T13:27:13","guid":{"rendered":"https:\/\/staging.fujifilmprint.eu\/?post_type=lp&#038;p=19570"},"modified":"2025-04-10T14:33:36","modified_gmt":"2025-04-10T13:33:36","slug":"fespa2025","status":"publish","type":"lp","link":"https:\/\/fujifilmprint.eu\/fr\/lp\/fespa2025\/","title":{"rendered":"FESPA 2025"},"content":{"rendered":"<section id=\"study-header\">\r\n\t<div class=\"container-fluid black-pt\" style=\"background-image: url('https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/Fespa-webpage-header-v1-scaled.jpg');background-size: cover;padding: 0;\">\r\n\t<div class=\"overlay\" style=\"padding: 200px 0;\">\t\t<div class=\"container\">\r\n\t\t\t<h3>\r\n\t\t\t\tFujifilm \u00e0\t\t\t<\/h3>\r\n\t\t\t<h2>\r\n\t\t\t\tFESPA 2025\t\t\t<\/h2>\r\n\t\t<\/div>\r\n\t<\/div>\t<\/div>\r\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<section id=\"tc-icons\">\n\t<div class=\"container block-three-column-icons\">\n\t\t<h2><\/h2>\n\t\t<div class=\"row\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/time.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Date<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">6 - 9 mai 2025<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/location_icon.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Emplacement<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Foire de Berlin<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"col-sm\">\n\t\t\t\t\t\t\t<div class=\"poi-icons\" style=\"\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/themes\/poi\/media\/icons\/stand.svg\" style=\"filter: brightness(0);\" \/>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<p>\n\t\t\t\t\t\t\t<strong>Stand<\/strong>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<p style=\"padding: 0 15px;\">Hall 25, stand B60<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/section>\n\n\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3><\/h3>\n\t\t<h2>Lancements de produits majeurs \u00e0 la FESPA Berlin 2025<\/h2>\n\t\t<p><p>C'est la premi\u00e8re fois que Fujifilm participe au salon depuis 2023, et nous sommes fiers de pr\u00e9senter l'Acuity Ultra Hybrid Pro, la solution HS3000 \u00e0 passage unique, et l'Acuity Triton avec la technologie d'encre AQUAFUZE. Ces solutions innovantes ont \u00e9t\u00e9 con\u00e7ues pour r\u00e9pondre aux divers besoins des diff\u00e9rents segments de march\u00e9, en offrant une polyvalence, une productivit\u00e9 et une qualit\u00e9 in\u00e9gal\u00e9es.<\/p>\n<p>Venez nous rendre visite aux stands B60 et A61 dans le hall 25 pour d\u00e9couvrir ces produits de pointe et voir comment Fujifilm ouvre la voie \u00e0 l'industrie de l'impression grand format gr\u00e2ce \u00e0 ses technologies r\u00e9volutionnaires.<\/p>\n<p><span style=\"color: #000000\">Voici la liste compl\u00e8te des solutions qui seront pr\u00e9sent\u00e9es sur le stand :<\/span><\/p>\n<h2><\/h2>\n<\/p>\n\t<\/div>\n<\/section>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3> Flexibilit\u00e9 de la production<\/h3>\n\t\t<h2>Acuity Ultra Hybrid Pro<\/h2>\n\t\t<p><p><span style=\"color: #000000\"><strong><span style=\"color: #ff00ff\">NOUVEAU<\/span> Acuity Ultra Hybrid Pro<\/strong><\/span><\/p>\n<p>L'Acuity Ultra Hybrid Pro est une solution polyvalente et productive pour les entreprises d'impression, permettant aux utilisateurs de traiter des travaux \u00e0 long, court ou ultra-court tirage sur des supports en rouleau et rigides. Gr\u00e2ce \u00e0 la technologie d'encre brevet\u00e9e Fujifilm, cette imprimante offre une qualit\u00e9 d'impression exceptionnelle avec une faible consommation d'encre. Elle dispose d'une largeur d'impression de 3,3 m, de t\u00eates d'impression Kyocera robustes et d'une configuration d'encre CMJN + Lc Lm W pour une pr\u00e9cision des couleurs exceptionnelle.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20084 aligncenter\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-1024x507.png\" alt=\"\" width=\"800\" height=\"396\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-1024x507.png 1024w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-300x149.png 300w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-768x380.png 768w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-1536x761.png 1536w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-2048x1014.png 2048w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Ultra-Hybrid-Pro-e1744190772180-18x9.png 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>L'imprimante peut \u00eatre int\u00e9gr\u00e9e \u00e0 un nouveau syst\u00e8me d'automatisation pour la production de gros volumes, offrant des options de semi-automatisation ou d'automatisation compl\u00e8te et une manipulation efficace des mat\u00e9riaux. L'Acuity Ultra Hybrid Pro sera commercialis\u00e9e peu apr\u00e8s la FESPA.<\/p>\n<\/p>\n\t<\/div>\n<\/section>\n\n<div style=\"height:20px;\">\n<\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3>Solutions \u00e0 passage unique pour les enseignes et les pr\u00e9sentoirs<\/h3>\n\t\t<h2>Fujifilm &amp; Barberan<\/h2>\n\t\t<p><p><span style=\"color: #000000\"><strong><span style=\"color: #ff00ff\">NOUVEAU <\/span><\/strong><\/span><strong>HS3000 et HS6000<\/strong><\/p>\n<p>Fujifilm et Barberan ont d\u00e9velopp\u00e9 des solutions jet d'encre \u00e0 passage unique pour le march\u00e9 de la signalisation et de l'affichage, notamment la HS6000 \u00e0 grande vitesse et la HS3000 r\u00e9cemment lanc\u00e9e avec des capacit\u00e9s de volume plus faibles. Ces imprimantes offrent une nouvelle g\u00e9n\u00e9ration de technologie d'impression en un seul passage, avec des t\u00eates d'impression haute r\u00e9solution et des gouttelettes de petite taille pour une qualit\u00e9 et une vitesse accrues. Les machines peuvent \u00eatre configur\u00e9es en fonction des pr\u00e9f\u00e9rences individuelles et des besoins de l'entreprise, avec des options d'alimentation manuelle ou de syst\u00e8mes automatis\u00e9s. La Fujifilm propose plusieurs jeux d'encre pour diverses applications, ce qui permet d'imprimer sur de nombreux types de supports sans qu'il soit n\u00e9cessaire d'utiliser un appr\u00eat.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20088 alignleft\" style=\"font-family: Poppins, sans-serif;font-size: 18px\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-1024x875.png\" alt=\"\" width=\"421\" height=\"360\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-1024x875.png 1024w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-300x256.png 300w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-768x657.png 768w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-1536x1313.png 1536w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856-14x12.png 14w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_HS3000-e1744190878856.png 1626w\" sizes=\"auto, (max-width: 421px) 100vw, 421px\" \/><\/p>\n<p>Cela permet de r\u00e9duire les consommables, la consommation d'\u00e9nergie et le co\u00fbt global par copie. Les imprimantes se composent de cinq \u00e9l\u00e9ments principaux - chargeur, primaire, moteur d'impression, vernis de surimpression et empileur - avec de nombreuses options de configuration disponibles pour la personnalisation.<\/p>\n<p>Un configurateur interactif sera pr\u00e9sent\u00e9 sur le stand pour permettre aux clients potentiels d'adapter la machine \u00e0 leurs besoins, et une journ\u00e9e portes ouvertes organis\u00e9e au cours de l'\u00e9t\u00e9 permettra aux parties int\u00e9ress\u00e9es d'en savoir plus sur ces solutions innovantes.<\/p>\n<\/p>\n\t<\/div>\n<\/section>\n\n<div style=\"height:80px;\">\n<\/div>\n\n<section id=\"txt-header\">\n\t<div class=\"container block-text-header\">\n\t\t<h3>Technologie d'encre AQUAFUZE <\/h3>\n\t\t<h2>Acuity Triton <\/h2>\n\t\t<p><p><span style=\"color: #000000\"><strong><span style=\"color: #ff00ff\">NOUVEAU <\/span><\/strong><\/span><strong>Acuity Triton avec AQUAFUZE<\/strong><\/p>\n<p>Fujifilm pr\u00e9sente une technologie d'encre r\u00e9volutionnaire, AQUAFUZE, qui cr\u00e9e des impressions durables adapt\u00e9es \u00e0 une utilisation int\u00e9rieure et ext\u00e9rieure sans n\u00e9cessiter de couche de finition. AQUAFUZE combine les avantages de l'impression LED UV et de l'impression jet d'encre \u00e0 base d'eau, offrant une forte adh\u00e9rence \u00e0 divers supports sans primaire, une consommation d'\u00e9nergie r\u00e9duite et une production \u00e0 faible odeur. Lanc\u00e9e avec l'imprimante Acuity Triton \u00e0 la FESPA, cette machine fabriqu\u00e9e au Japon exploite AQUAFUZE pour offrir une impression rentable et \u00e9conome en \u00e9nergie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20085 alignright\" src=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-1024x687.png\" alt=\"\" width=\"485\" height=\"325\" srcset=\"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-1024x687.png 1024w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-300x201.png 300w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-768x515.png 768w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-1536x1031.png 1536w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484-18x12.png 18w, https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2025\/04\/tetragon_Acuity-Triton-e1744191105484.png 1620w\" sizes=\"auto, (max-width: 485px) 100vw, 485px\" \/><\/p>\n<p>L'Acuity Triton, avec une largeur d'impression de 1,6 m, produit des impressions de haute qualit\u00e9 \u00e0 des vitesses allant jusqu'\u00e0 15 m\u00b2\/h, avec un s\u00e9chage instantan\u00e9 pour une finition imm\u00e9diate. Le s\u00e9chage \u00e0 basse temp\u00e9rature de l'AQUAFUZE minimise les blocages des buses et r\u00e9duit la consommation d'\u00e9nergie, ce qui en fait la solution id\u00e9ale pour les entreprises durables de toutes tailles.<\/p>\n<p>L'Acuity Triton sera disponible chez les revendeurs, et les clients du grand format seront invit\u00e9s \u00e0 d\u00e9couvrir cette solution innovante \u00e0 la FESPA. Le d\u00e9ploiement se fera au niveau r\u00e9gional, sur la base des accords de concession existants, et de plus amples d\u00e9tails seront fournis lors de l'\u00e9v\u00e9nement.<\/p>\n<\/p>\n\t<\/div>\n<\/section>\n\n<div style=\"height:50px;\">\n<\/div>\n\n<div id=\"contact\"><\/div>\n\n<section id=\"dark-form\">\n\t<div id=\"footer-form\" class=\"container\">\n\t\t<h2>Vous allez \u00e0 la FESPA 2025 ? Faites-le nous savoir :<\/h2>\n\n\t\tMktoForms2.loadForm(\u201c\/\/info.fujifilm.eu\u201d, \u201c060-MIY-956\u201d, 5264);\n\t\t<div id=\"confirmform\" style=\"visibility:hidden;\">\n                            <p><strong>\n\t\t\t\t\tMerci pour votre demande, quelqu&#039;un vous contactera bient\u00f4t.\t\t\t\t\t<\/strong><\/p>\n              \n        <\/div>\n\t<\/div>\n<\/section>","protected":false},"template":"","class_list":["post-19570","lp","type-lp","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FESPA 2025 | Fujifilm Print EMEA<\/title>\n<meta name=\"description\" content=\"Come visit us at stands B60 and A61 in Hall 25 to experience these cutting-edge products firsthand and see how we, at Fujifilm, are leading the way in the wide format print industry with our revolutionary technologies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fujifilmprint.eu\/fr\/lp\/fespa2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FESPA 2025 | Fujifilm Print EMEA\" \/>\n<meta property=\"og:description\" content=\"Come visit us at stands B60 and A61 in Hall 25 to experience these cutting-edge products firsthand and see how we, at Fujifilm, are leading the way in the wide format print industry with our revolutionary technologies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fujifilmprint.eu\/fr\/lp\/fespa2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fujifilm Print EMEA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T13:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/fespa2025\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/fespa2025\\\/\",\"name\":\"FESPA 2025 | Fujifilm Print EMEA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\"},\"datePublished\":\"2025-04-10T13:27:13+00:00\",\"dateModified\":\"2025-04-10T13:33:36+00:00\",\"description\":\"Come visit us at stands B60 and A61 in Hall 25 to experience these cutting-edge products firsthand and see how we, at Fujifilm, are leading the way in the wide format print industry with our revolutionary technologies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/fespa2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/fespa2025\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/fespa2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landing Pages\",\"item\":\"https:\\\/\\\/fujifilmprint.eu\\\/lp\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FESPA 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#website\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"name\":\"Fujifilm Print EMEA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fujifilmprint.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#organization\",\"name\":\"Fujifilm Print EMEA\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"contentUrl\":\"https:\\\/\\\/fujifilmprint.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/fujifilm-1.png\",\"width\":416,\"height\":70,\"caption\":\"Fujifilm Print EMEA\"},\"image\":{\"@id\":\"https:\\\/\\\/fujifilmprint.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FESPA 2025 | Fujifilm Print EMEA","description":"Venez nous rendre visite aux stands B60 et A61 dans le hall 25 pour d\u00e9couvrir ces produits de pointe et voir comment Fujifilm ouvre la voie \u00e0 l'industrie de l'impression grand format gr\u00e2ce \u00e0 ses technologies r\u00e9volutionnaires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fujifilmprint.eu\/fr\/lp\/fespa2025\/","og_locale":"fr_FR","og_type":"article","og_title":"FESPA 2025 | Fujifilm Print EMEA","og_description":"Come visit us at stands B60 and A61 in Hall 25 to experience these cutting-edge products firsthand and see how we, at Fujifilm, are leading the way in the wide format print industry with our revolutionary technologies.","og_url":"https:\/\/fujifilmprint.eu\/fr\/lp\/fespa2025\/","og_site_name":"Fujifilm Print EMEA","article_modified_time":"2025-04-10T13:33:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fujifilmprint.eu\/lp\/fespa2025\/","url":"https:\/\/fujifilmprint.eu\/lp\/fespa2025\/","name":"FESPA 2025 | Fujifilm Print EMEA","isPartOf":{"@id":"https:\/\/fujifilmprint.eu\/#website"},"datePublished":"2025-04-10T13:27:13+00:00","dateModified":"2025-04-10T13:33:36+00:00","description":"Venez nous rendre visite aux stands B60 et A61 dans le hall 25 pour d\u00e9couvrir ces produits de pointe et voir comment Fujifilm ouvre la voie \u00e0 l'industrie de l'impression grand format gr\u00e2ce \u00e0 ses technologies r\u00e9volutionnaires.","breadcrumb":{"@id":"https:\/\/fujifilmprint.eu\/lp\/fespa2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fujifilmprint.eu\/lp\/fespa2025\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fujifilmprint.eu\/lp\/fespa2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fujifilmprint.eu\/"},{"@type":"ListItem","position":2,"name":"Landing Pages","item":"https:\/\/fujifilmprint.eu\/lp\/"},{"@type":"ListItem","position":3,"name":"FESPA 2025"}]},{"@type":"WebSite","@id":"https:\/\/fujifilmprint.eu\/#website","url":"https:\/\/fujifilmprint.eu\/","name":"Fujifilm Imprimer EMEA","description":"","publisher":{"@id":"https:\/\/fujifilmprint.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fujifilmprint.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fujifilmprint.eu\/#organization","name":"Fujifilm Imprimer EMEA","url":"https:\/\/fujifilmprint.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/","url":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","contentUrl":"https:\/\/fujifilmprint.eu\/wp-content\/uploads\/2022\/07\/fujifilm-1.png","width":416,"height":70,"caption":"Fujifilm Print EMEA"},"image":{"@id":"https:\/\/fujifilmprint.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/lp\/19570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/lp"}],"about":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/types\/lp"}],"wp:attachment":[{"href":"https:\/\/fujifilmprint.eu\/fr\/wp-json\/wp\/v2\/media?parent=19570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}